{"id":4763,"date":"2024-03-18T13:00:48","date_gmt":"2024-03-18T12:00:48","guid":{"rendered":"https:\/\/www.auresa.de\/blog\/?p=4763"},"modified":"2025-02-07T14:56:36","modified_gmt":"2025-02-07T13:56:36","slug":"aus-was-besteht-gruener-tee","status":"publish","type":"post","link":"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/","title":{"rendered":"Aus was besteht gr\u00fcner Tee?"},"content":{"rendered":"<p>Gr\u00fcner Tee ist nicht nur eine der beliebtesten Tee Sorten, sondern auch die \u00e4lteste. Seinen gro\u00dfen Auftritt hatte Gr\u00fcntee vor etwa 5000 Jahren im alten China. Nach Europa kam er allerdings erst vor knapp 400 Jahren, verbreitete sich dort allerdings umso schneller auf dem gesamten Kontinent. Aber aus was besteht gr\u00fcner Tee eigentlich? Wir enth\u00fcllen das Geheimnis, warum der Tee so beliebt ist.<!--more--><\/p>\n<h2><strong>Was macht gr\u00fcnen Tee so beliebt?<\/strong><\/h2>\n<p><a title=\"Bio Gunpowder\" href=\"https:\/\/www.auresa.de\/bio-gunpowder\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4424 alignright\" src=\"https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2020\/03\/10134-91247-300x284.jpg\" alt=\"Loser Tee Gunpowder\" width=\"300\" height=\"284\" srcset=\"https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2020\/03\/10134-91247-300x284.jpg 300w, https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2020\/03\/10134-91247-768x727.jpg 768w, https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2020\/03\/10134-91247.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Blickt man auf den weltweiten Teekonsum, so ist <a title=\"Gr\u00fcner Tee\" href=\"https:\/\/www.auresa.de\/gruener-tee\/\" target=\"_blank\" rel=\"noopener\">gr\u00fcner Tee<\/a> hier auf Platz 1. In unseren Breitengraden sieht das geringf\u00fcgig anders aus, denn dort ist schwarzer Tee die am meisten getrunkene Tee Sorte. Allerdings befindet sich auch hier der gr\u00fcne Tee langsam aber sicher auf der \u00dcberholspur, was daran liegt, dass immer mehr Menschen die Vorz\u00fcge von gr\u00fcnem Tee f\u00fcr sich entdecken.<\/p>\n<p>Denn zum einen handelt es sich auch bei gr\u00fcnem Tee um ein koffeinhaltiges Getr\u00e4nk, das damit selbstverst\u00e4ndlich auch \u00fcber eine wachmachende Wirkung verf\u00fcgt. Je nach Gr\u00fcntee Sorte kommt man hier auf 10 bis 45 Milligramm Koffein pro Tasse. Gerade etwas st\u00e4rkere Sorten wie beispielsweise <a title=\"Bio Gunpowder\" href=\"https:\/\/www.auresa.de\/bio-gunpowder\" target=\"_blank\" rel=\"noopener\">Gunpowder Tee<\/a> werden deshalb oftmals gerne zum Fr\u00fchst\u00fcck als Kaffee-Ersatz getrunken.<\/p>\n<p>Auch wenn es um die Sortenvielfalt geht, so punktet hier der gr\u00fcne Tee. Denn je nach Anbaugebiet und Verarbeitungsweise kann gr\u00fcner Tee s\u00fc\u00df, fruchtig, grasig, blumig oder auch w\u00fcrzig schmecken. Es gibt also f\u00fcr jeden Geschmack den passenden Gr\u00fcntee. Zudem schmeckt gr\u00fcner Tee auch kalt sehr lecker und ist damit ein toller Tee f\u00fcr den Sommer.<\/p>\n<p>Gr\u00fcner Tee kann zudem auch mehrfach aufgegossen werden und ist somit sehr ergiebig. Denn je nach Qualit\u00e4t des Tees und Art der Zubereitung sind hier bis zu 5 Aufg\u00fcsse pro Portion Teebl\u00e4tter m\u00f6glich!<\/p>\n<h2><strong>Aus was wird gr\u00fcner Tee hergestellt?<\/strong><\/h2>\n<p><a title=\"Bio Nebeltee\" href=\"https:\/\/www.auresa.de\/bio-nebeltee\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4477 alignleft\" src=\"https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2022\/11\/10142-91501-300x293.jpg\" alt=\"Loser Tee Bio Nebeltee\" width=\"300\" height=\"293\" srcset=\"https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2022\/11\/10142-91501-300x293.jpg 300w, https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2022\/11\/10142-91501-768x749.jpg 768w, https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2022\/11\/10142-91501.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Gr\u00fcner Tee besteht aus den Bl\u00e4ttern der Teepflanze Camellia Sinensis \u2013 wie \u00fcbrigens jede andere Tee Sorte auch. Denn tats\u00e4chlich haben gr\u00fcner Tee, <a title=\"Schwarzer Tee\" href=\"https:\/\/www.auresa.de\/schwarzer-tee\/\" target=\"_blank\" rel=\"noopener\">schwarzer Tee<\/a>, wei\u00dfer Tee und <a title=\"Oolong Tee\" href=\"https:\/\/www.auresa.de\/oolong-tee\/\" target=\"_blank\" rel=\"noopener\">Oolong Tee<\/a> alle das gleiche Ausgangsmaterial. Die Art und Weise, wie die Teebl\u00e4tter nach der Ernte weiterverarbeitet werden, entscheidet schlussendlich \u00fcber die Tee Sorte. Denn w\u00e4hrend schwarzer Tee und Oolong Tee komplett oder zumindest teilweise oxidiert werden, findet bei gr\u00fcnem Tee \u00fcberhaupt keine Oxidation statt. Diese wird hier entweder durch R\u00f6sten in einer Eisenpfanne oder durch hei\u00dfen Wasserdampf unterbunden. Auf diese Weise beh\u00e4lt gr\u00fcner Tee seine namensgebende Farbe und seinen grasig-frischen Geschmack.<\/p>\n<p>Die Teepflanze bildet Koffein aus, um sich vor Sch\u00e4dlingen zu sch\u00fctzen. Das meiste Koffein wird dabei in den Bl\u00e4ttern gebildet. Folglich ist auch gr\u00fcner Tee, der aus eben diesen Bl\u00e4ttern besteht, koffeinhaltig. Allerdings enth\u00e4lt gr\u00fcner Tee nicht nur Koffein, sondern auch sogenannte Gerbstoffe. Diese sorgen daf\u00fcr, dass das Koffein bei gr\u00fcnem Tee anders wirkt als bei Kaffee. Denn die Gerbstoffe binden das Koffein an sich. Diese Verbindungen m\u00fcssen zuerst bei uns im Darm wieder gel\u00f6st werden, bevor das Koffein seine Wirkung entfalten kann. Die Wirkung des Koffeins setzt daher langsamer ein und h\u00e4lt daf\u00fcr aber auch l\u00e4nger an als bei Kaffee.<\/p>\n<h2><strong>Die richtige Zubereitung von gr\u00fcnem Tee<\/strong><\/h2>\n<p><a title=\"Genmaicha\" href=\"https:\/\/www.auresa.de\/genmaicha\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1676 alignright\" src=\"https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2019\/08\/10265-90551-300x280.jpg\" alt=\"Loser gr\u00fcner Tee Genmaicha\" width=\"300\" height=\"280\" srcset=\"https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2019\/08\/10265-90551-300x280.jpg 300w, https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2019\/08\/10265-90551-768x716.jpg 768w, https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2019\/08\/10265-90551.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Immer wieder taucht die Behauptung auf, die Zubereitung von gr\u00fcnem Tee sei kompliziert. Tats\u00e4chlich muss man bei der Zubereitung von Gr\u00fcntee ein paar zus\u00e4tzliche Punkte beachten, die es beispielsweise bei Schwarztee, <a title=\"Fr\u00fcchtetee\" href=\"https:\/\/www.auresa.de\/fruechtetee\/\" target=\"_blank\" rel=\"noopener\">Fr\u00fcchtetee<\/a> oder <a title=\"Kr\u00e4utertee\" href=\"https:\/\/www.auresa.de\/kraeutertee\/\" target=\"_blank\" rel=\"noopener\">Kr\u00e4utertee<\/a> nicht zu beachten gibt. Denn gr\u00fcner Tee darf nicht mit noch sprudelnd-kochendem Wasser aufgegossen werden, da er sonst bitter wird. Die Aufgusstemperatur bewegt sich bei gr\u00fcnem Tee zwischen 60 und 80 Grad Celsius. Auch die Ziehzeit ist k\u00fcrzer als bei anderen Tee Sorten, denn sie betr\u00e4gt 2 Minuten.<\/p>\n<p>Sie haben Lust bekommen, die Welt des Gr\u00fcntees zu entdecken? Dann schauen Sie mal bei unseren <a title=\"Probiersets\" href=\"https:\/\/www.auresa.de\/probiersets\/\" target=\"_blank\" rel=\"noopener\">Probiersets<\/a> vorbei! Unser <a title=\"Gr\u00fcntee Probierset\" href=\"https:\/\/www.auresa.de\/gruentee-probierset\" target=\"_blank\" rel=\"noopener\">Gr\u00fcntee Probierset<\/a> enth\u00e4lt alle unsere gr\u00fcnen Tees in praktischen Probiergr\u00f6\u00dfen.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" data-services=\"facebook\" data-url=\"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/\" data-timestamp=\"1738940196\" data-backendurl=\"https:\/\/www.auresa.de\/blog\/wp-json\/shariff\/v1\/share_counts?\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.auresa.de%2Fblog%2Faus-was-besteht-gruener-tee%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fwww.auresa.de%2Fblog%2Faus-was-besteht-gruener-tee%2F&text=Aus%20was%20besteht%20gr%C3%BCner%20Tee%3F\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Gr\u00fcner Tee ist nicht nur eine der beliebtesten Tee Sorten, sondern auch die \u00e4lteste. Seinen gro\u00dfen Auftritt hatte Gr\u00fcntee vor etwa 5000 Jahren im alten China. Nach Europa kam er allerdings erst vor knapp 400 Jahren, verbreitete sich dort allerdings umso schneller auf dem gesamten Kontinent. Aber aus was besteht gr\u00fcner Tee eigentlich? Wir enth\u00fcllen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4765,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-4763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-teesorten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aus was besteht gr\u00fcner Tee? - AURESA Blog<\/title>\n<meta name=\"description\" content=\"Gr\u00fcner Tee ist die \u00e4lteste und beliebteste Teesorte. Aber aus was besteht gr\u00fcner Tee eigentlich? Das erkl\u00e4ren wir Ihnen in diesem Beitrag.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aus was besteht gr\u00fcner Tee? - AURESA Blog\" \/>\n<meta property=\"og:description\" content=\"Gr\u00fcner Tee ist die \u00e4lteste und beliebteste Teesorte. Aber aus was besteht gr\u00fcner Tee eigentlich? Das erkl\u00e4ren wir Ihnen in diesem Beitrag.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/\" \/>\n<meta property=\"og:site_name\" content=\"AURESA Blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-18T12:00:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-07T13:56:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2024\/03\/aus-was-besteht-gruener-zee.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sarah Niederb\u00fchl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sarah Niederb\u00fchl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/aus-was-besteht-gruener-tee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/aus-was-besteht-gruener-tee\\\/\"},\"author\":{\"name\":\"Sarah Niederb\u00fchl\",\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/#\\\/schema\\\/person\\\/118ae9d927aea2db58d68aea714d9cf7\"},\"headline\":\"Aus was besteht gr\u00fcner Tee?\",\"datePublished\":\"2024-03-18T12:00:48+00:00\",\"dateModified\":\"2025-02-07T13:56:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/aus-was-besteht-gruener-tee\\\/\"},\"wordCount\":670,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/aus-was-besteht-gruener-tee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/aus-was-besteht-gruener-zee.jpg\",\"articleSection\":[\"Teesorten\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.auresa.de\\\/blog\\\/aus-was-besteht-gruener-tee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/aus-was-besteht-gruener-tee\\\/\",\"url\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/aus-was-besteht-gruener-tee\\\/\",\"name\":\"Aus was besteht gr\u00fcner Tee? - AURESA Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/aus-was-besteht-gruener-tee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/aus-was-besteht-gruener-tee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/aus-was-besteht-gruener-zee.jpg\",\"datePublished\":\"2024-03-18T12:00:48+00:00\",\"dateModified\":\"2025-02-07T13:56:36+00:00\",\"description\":\"Gr\u00fcner Tee ist die \u00e4lteste und beliebteste Teesorte. Aber aus was besteht gr\u00fcner Tee eigentlich? Das erkl\u00e4ren wir Ihnen in diesem Beitrag.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/aus-was-besteht-gruener-tee\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auresa.de\\\/blog\\\/aus-was-besteht-gruener-tee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/aus-was-besteht-gruener-tee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/aus-was-besteht-gruener-zee.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/aus-was-besteht-gruener-zee.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/aus-was-besteht-gruener-tee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aus was besteht gr\u00fcner Tee?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/\",\"name\":\"AURESA Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/#organization\",\"name\":\"AURESA\",\"url\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/auresa-logo-copyright.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/auresa-logo-copyright.jpg\",\"width\":2866,\"height\":856,\"caption\":\"AURESA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/#\\\/schema\\\/person\\\/118ae9d927aea2db58d68aea714d9cf7\",\"name\":\"Sarah Niederb\u00fchl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9318a589fd1e4be79a14d53d5af71f8a26acb40419eb26782565617103fac512?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9318a589fd1e4be79a14d53d5af71f8a26acb40419eb26782565617103fac512?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9318a589fd1e4be79a14d53d5af71f8a26acb40419eb26782565617103fac512?s=96&d=mm&r=g\",\"caption\":\"Sarah Niederb\u00fchl\"},\"url\":\"https:\\\/\\\/www.auresa.de\\\/blog\\\/author\\\/sarah-niederbuehl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aus was besteht gr\u00fcner Tee? - AURESA Blog","description":"Gr\u00fcner Tee ist die \u00e4lteste und beliebteste Teesorte. Aber aus was besteht gr\u00fcner Tee eigentlich? Das erkl\u00e4ren wir Ihnen in diesem Beitrag.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/","og_locale":"de_DE","og_type":"article","og_title":"Aus was besteht gr\u00fcner Tee? - AURESA Blog","og_description":"Gr\u00fcner Tee ist die \u00e4lteste und beliebteste Teesorte. Aber aus was besteht gr\u00fcner Tee eigentlich? Das erkl\u00e4ren wir Ihnen in diesem Beitrag.","og_url":"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/","og_site_name":"AURESA Blog","article_published_time":"2024-03-18T12:00:48+00:00","article_modified_time":"2025-02-07T13:56:36+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2024\/03\/aus-was-besteht-gruener-zee.jpg","type":"image\/jpeg"}],"author":"Sarah Niederb\u00fchl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Sarah Niederb\u00fchl","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/#article","isPartOf":{"@id":"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/"},"author":{"name":"Sarah Niederb\u00fchl","@id":"https:\/\/www.auresa.de\/blog\/#\/schema\/person\/118ae9d927aea2db58d68aea714d9cf7"},"headline":"Aus was besteht gr\u00fcner Tee?","datePublished":"2024-03-18T12:00:48+00:00","dateModified":"2025-02-07T13:56:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/"},"wordCount":670,"commentCount":0,"publisher":{"@id":"https:\/\/www.auresa.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2024\/03\/aus-was-besteht-gruener-zee.jpg","articleSection":["Teesorten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/","url":"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/","name":"Aus was besteht gr\u00fcner Tee? - AURESA Blog","isPartOf":{"@id":"https:\/\/www.auresa.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/#primaryimage"},"image":{"@id":"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2024\/03\/aus-was-besteht-gruener-zee.jpg","datePublished":"2024-03-18T12:00:48+00:00","dateModified":"2025-02-07T13:56:36+00:00","description":"Gr\u00fcner Tee ist die \u00e4lteste und beliebteste Teesorte. Aber aus was besteht gr\u00fcner Tee eigentlich? Das erkl\u00e4ren wir Ihnen in diesem Beitrag.","breadcrumb":{"@id":"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/#primaryimage","url":"https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2024\/03\/aus-was-besteht-gruener-zee.jpg","contentUrl":"https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2024\/03\/aus-was-besteht-gruener-zee.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.auresa.de\/blog\/aus-was-besteht-gruener-tee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.auresa.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Aus was besteht gr\u00fcner Tee?"}]},{"@type":"WebSite","@id":"https:\/\/www.auresa.de\/blog\/#website","url":"https:\/\/www.auresa.de\/blog\/","name":"AURESA Blog","description":"","publisher":{"@id":"https:\/\/www.auresa.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auresa.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.auresa.de\/blog\/#organization","name":"AURESA","url":"https:\/\/www.auresa.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.auresa.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2019\/08\/auresa-logo-copyright.jpg","contentUrl":"https:\/\/www.auresa.de\/blog\/wp-content\/uploads\/2019\/08\/auresa-logo-copyright.jpg","width":2866,"height":856,"caption":"AURESA"},"image":{"@id":"https:\/\/www.auresa.de\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.auresa.de\/blog\/#\/schema\/person\/118ae9d927aea2db58d68aea714d9cf7","name":"Sarah Niederb\u00fchl","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/9318a589fd1e4be79a14d53d5af71f8a26acb40419eb26782565617103fac512?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9318a589fd1e4be79a14d53d5af71f8a26acb40419eb26782565617103fac512?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9318a589fd1e4be79a14d53d5af71f8a26acb40419eb26782565617103fac512?s=96&d=mm&r=g","caption":"Sarah Niederb\u00fchl"},"url":"https:\/\/www.auresa.de\/blog\/author\/sarah-niederbuehl\/"}]}},"_links":{"self":[{"href":"https:\/\/www.auresa.de\/blog\/wp-json\/wp\/v2\/posts\/4763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auresa.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.auresa.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.auresa.de\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.auresa.de\/blog\/wp-json\/wp\/v2\/comments?post=4763"}],"version-history":[{"count":6,"href":"https:\/\/www.auresa.de\/blog\/wp-json\/wp\/v2\/posts\/4763\/revisions"}],"predecessor-version":[{"id":5422,"href":"https:\/\/www.auresa.de\/blog\/wp-json\/wp\/v2\/posts\/4763\/revisions\/5422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auresa.de\/blog\/wp-json\/wp\/v2\/media\/4765"}],"wp:attachment":[{"href":"https:\/\/www.auresa.de\/blog\/wp-json\/wp\/v2\/media?parent=4763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.auresa.de\/blog\/wp-json\/wp\/v2\/categories?post=4763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.auresa.de\/blog\/wp-json\/wp\/v2\/tags?post=4763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}